{"id":6653,"date":"2023-10-03T20:49:12","date_gmt":"2023-10-03T20:49:12","guid":{"rendered":"https:\/\/www.darumasushiantofagasta.cl\/menu\/?post_type=product&#038;p=6653"},"modified":"2025-01-09T20:50:11","modified_gmt":"2025-01-09T23:50:11","slug":"trio-nikkei","status":"publish","type":"product","link":"https:\/\/www.darumasushiantofagasta.cl\/menu\/producto\/trio-nikkei\/","title":{"rendered":"TRIO NIKKEI"},"content":{"rendered":"<p>\u2022\tCrisp\u00ed causa (causa lime\u00f1a crocante coronado con cebiche de rocoto)<br \/>\n\u2022\tBrocheta de pescado en salsa marina<br \/>\n\u2022\tPulpo grillado [tent\u00e1culos de pulpo a la parrilla]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022\tCrisp\u00ed causa (causa lime\u00f1a crocante coronado con cebiche de rocoto)<br \/>\n\u2022\tBrocheta de pescado en salsa marina<br \/>\n\u2022\tPulpo grillado [tent\u00e1culos de pulpo a la parrilla]<\/p>\n","protected":false},"featured_media":6253,"template":"","meta":[],"product_brand":[],"product_cat":[203],"product_tag":[],"class_list":{"0":"post-6653","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-especiales","7":"tm-has-options","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product\/6653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/media\/6253"}],"wp:attachment":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/media?parent=6653"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_brand?post=6653"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_cat?post=6653"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_tag?post=6653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}