{"id":6647,"date":"2023-10-03T20:49:06","date_gmt":"2023-10-03T20:49:06","guid":{"rendered":"https:\/\/www.darumasushiantofagasta.cl\/menu\/?post_type=product&#038;p=6647"},"modified":"2025-10-17T17:03:09","modified_gmt":"2025-10-17T20:03:09","slug":"porky-ramen","status":"publish","type":"product","link":"https:\/\/www.darumasushiantofagasta.cl\/menu\/producto\/porky-ramen\/","title":{"rendered":"PORKY RAMEN"},"content":{"rendered":"<p>Noodles, caldo picoso, porci\u00f3n de cerdo cocinado estilo char-siu, brotes de soya, col blanca, hongos shitake y rulos de nabo y nori<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noodles, caldo picoso, porci\u00f3n de cerdo cocinado estilo char-siu, brotes de soya, col blanca, hongos shitake y rulos de nabo y nori<\/p>\n","protected":false},"featured_media":6253,"template":"","meta":[],"product_brand":[],"product_cat":[200],"product_tag":[],"class_list":{"0":"post-6647","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-platos-calientes","7":"tm-has-options","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product\/6647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/media\/6253"}],"wp:attachment":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/media?parent=6647"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_brand?post=6647"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_cat?post=6647"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_tag?post=6647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}