{"id":6640,"date":"2023-10-03T20:49:06","date_gmt":"2023-10-03T20:49:06","guid":{"rendered":"https:\/\/www.darumasushiantofagasta.cl\/menu\/?post_type=product&#038;p=6640"},"modified":"2025-01-09T20:50:06","modified_gmt":"2025-01-09T23:50:06","slug":"cevichito-nikkei","status":"publish","type":"product","link":"https:\/\/www.darumasushiantofagasta.cl\/menu\/producto\/cevichito-nikkei\/","title":{"rendered":"CEVICHITO NIKKEI"},"content":{"rendered":"<p>At\u00fan estilo tataki en cubos, aros cebolla roja, camote, mango en trozos, palta sellada en cubos, canchita serrana y leche tigre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>At\u00fan estilo tataki en cubos, aros cebolla roja, camote, mango en trozos, palta sellada en cubos, canchita serrana y leche tigre<\/p>\n","protected":false},"featured_media":6253,"template":"","meta":[],"product_brand":[],"product_cat":[199],"product_tag":[],"class_list":{"0":"post-6640","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sushi-bar-frios","7":"tm-has-options","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product\/6640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/media\/6253"}],"wp:attachment":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/media?parent=6640"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_brand?post=6640"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_cat?post=6640"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_tag?post=6640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}