{"id":6637,"date":"2023-10-03T20:49:06","date_gmt":"2023-10-03T20:49:06","guid":{"rendered":"https:\/\/www.darumasushiantofagasta.cl\/menu\/?post_type=product&#038;p=6637"},"modified":"2025-10-17T18:08:15","modified_gmt":"2025-10-17T21:08:15","slug":"lomo-saltado","status":"publish","type":"product","link":"https:\/\/www.darumasushiantofagasta.cl\/menu\/producto\/lomo-saltado\/","title":{"rendered":"Lomo Saltado"},"content":{"rendered":"<p>Trozos de lomo fino, saltados con verduras,acompa\u00f1ado con papas fritas y arroz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trozos de lomo fino, saltados con verduras,acompa\u00f1ado con papas fritas y arroz<\/p>\n","protected":false},"featured_media":6253,"template":"","meta":[],"product_brand":[],"product_cat":[202],"product_tag":[],"class_list":{"0":"post-6637","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-parrilla","7":"tm-has-options","9":"first","10":"outofstock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product\/6637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/media\/6253"}],"wp:attachment":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/media?parent=6637"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_brand?post=6637"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_cat?post=6637"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_tag?post=6637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}