{"id":6596,"date":"2023-10-03T20:48:56","date_gmt":"2023-10-03T20:48:56","guid":{"rendered":"https:\/\/www.darumasushiantofagasta.cl\/menu\/?post_type=product&#038;p=6596"},"modified":"2025-01-09T20:49:56","modified_gmt":"2025-01-09T23:49:56","slug":"roll-ebicado","status":"publish","type":"product","link":"https:\/\/www.darumasushiantofagasta.cl\/menu\/producto\/roll-ebicado\/","title":{"rendered":"Roll Ebicado"},"content":{"rendered":"<p>Camaron cocido ,queso crema y finos cortes de cebollin (negui),cubierto de laminas de palta  y ba\u00f1ado en salsa Anguila\/Unagui<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Camaron cocido ,queso crema y finos cortes de cebollin (negui),cubierto de laminas de palta  y ba\u00f1ado en salsa Anguila\/Unagui<\/p>\n","protected":false},"featured_media":6253,"template":"","meta":[],"product_brand":[],"product_cat":[197],"product_tag":[],"class_list":{"0":"post-6596","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-roll-a-la-carta","7":"tm-has-options","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product\/6596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/media\/6253"}],"wp:attachment":[{"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/media?parent=6596"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_brand?post=6596"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_cat?post=6596"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.darumasushiantofagasta.cl\/menu\/wp-json\/wp\/v2\/product_tag?post=6596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}